{"id":9705,"date":"2019-09-06T15:00:45","date_gmt":"2019-09-06T08:00:45","guid":{"rendered":"https:\/\/www.memagazine.co.th?p=9705"},"modified":"2019-12-17T12:40:36","modified_gmt":"2019-12-17T05:40:36","slug":"%e0%b8%ae%e0%b8%ad%e0%b8%99%e0%b8%94%e0%b9%89%e0%b8%b2-%e0%b9%80%e0%b8%8a%e0%b8%b4%e0%b8%8d%e0%b8%aa%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%a1%e0%b8%a7%e0%b8%a5%e0%b8%8a%e0%b8%99%e0%b8%a3%e0%b9%88%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/www.memagazine.co.th\/en\/9705\/","title":{"rendered":"\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e0a\u0e34\u0e0d\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cLife Crossover Lifestyle Trip\u201d \u0e17\u0e14\u0e2a\u0e2d\u0e1a\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35 \u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35   \u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u2013 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c"},"content":{"rendered":"<p><a href=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-_Memag_Online.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-9706 aligncenter\" src=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-_Memag_Online.jpg\" alt=\"Honda Life Crossover Lifestyle Trip_Swimming _Memag_Online\" width=\"744\" height=\"531\" \/><\/a><\/p>\n<p><strong>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e0a\u0e34\u0e0d\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cLife Crossover Lifestyle Trip\u201d \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e22\u0e19\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e40\u0e2d\u0e2a\u0e22\u0e39\u0e27\u0e35 \u0e02\u0e2d\u0e07\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 2 \u0e23\u0e38\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u201c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35 \u0e43\u0e2b\u0e21\u0e48\u201d \u0e41\u0e25\u0e30 \u201c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35\u201d \u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u2013 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e27\u0e21\u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e01\u0e27\u0e48\u0e32 400 \u0e01\u0e34\u0e42\u0e25\u0e40\u0e21\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e38\u0e01\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e2d\u0e1b\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e04\u0e23\u0e2d\u0e2a\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e14\u0e49\u0e32\u0e19 (Life Crossover)<\/strong><\/p>\n<p><a href=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-3_resize.jpg\"><img loading=\"lazy\" class=\"size-large wp-image-9709 aligncenter\" src=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-3_resize-1024x684.jpg\" alt=\"Honda Life Crossover Lifestyle Trip_Swimming (3)_resize\" width=\"1024\" height=\"684\" \/><\/a><\/p>\n<p>\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32 \u0e04\u0e13\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e1e\u0e1a\u0e01\u0e31\u0e19 \u0e13 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2a\u0e32\u0e02\u0e32\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07 2 \u0e23\u0e38\u0e48\u0e19 \u0e04\u0e37\u0e2d <strong>\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c<\/strong><strong>-\u0e27\u0e35 \u0e43\u0e2b\u0e21\u0e48<\/strong> \u0e22\u0e19\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e04\u0e23\u0e2d\u0e2a\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e01\u0e23\u0e48\u0e07\u0e43\u0e19\u0e17\u0e38\u0e01\u0e21\u0e34\u0e15\u0e34 \u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e17\u0e38\u0e01\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e08\u0e31\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 \u0e44\u0e1f\u0e2b\u0e19\u0e49\u0e32\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e04\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1f\u0e2b\u0e23\u0e35\u0e48\u0e41\u0e25\u0e30\u0e44\u0e1f\u0e2a\u0e48\u0e2d\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e43\u0e19\u0e40\u0e27\u0e25\u0e32\u0e01\u0e25\u0e32\u0e07\u0e27\u0e31\u0e19\u0e41\u0e1a\u0e1a<strong> LED<\/strong> \u0e44\u0e1f\u0e15\u0e31\u0e14\u0e2b\u0e21\u0e2d\u0e01\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e43\u0e2b\u0e21\u0e48\u0e42\u0e09\u0e1a\u0e40\u0e09\u0e35\u0e48\u0e22\u0e27 \u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e38\u0e22\u0e17\u0e38\u0e01\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u00a0 \u0e41\u0e25\u0e30\u0e25\u0e49\u0e2d\u0e2d\u0e31\u0e25\u0e25\u0e2d\u0e22\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e35\u0e43\u0e2b\u0e21\u0e48 \u0e2a\u0e35\u0e41\u0e14\u0e07\u0e41\u0e1e\u0e2a\u0e0a\u0e31\u0e48\u0e19 (\u0e21\u0e38\u0e01) \u0e41\u0e25\u0e30<strong> \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c<\/strong><strong>-\u0e27\u0e35<\/strong>\u00a0 \u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e20\u0e32\u0e22\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e42\u0e09\u0e1a\u0e40\u0e09\u0e35\u0e48\u0e22\u0e27\u0e22\u0e34\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e1a\u0e48\u0e07\u0e1a\u0e2d\u0e01\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e15\u0e31\u0e27\u0e15\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e20\u0e32\u0e1e\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e22\u0e21\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e02\u0e31\u0e49\u0e19 \u0e01\u0e31\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2a\u0e35\u0e41\u0e14\u0e07\u0e2d\u0e2d\u0e01\u0e0b\u0e4c\u0e1a\u0e25\u0e31\u0e14 \u0e43\u0e19\u0e23\u0e38\u0e48\u0e19 RS \u0e41\u0e25\u0e30\u0e2a\u0e35\u0e17\u0e39\u0e42\u0e17\u0e19 \u0e44\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e35\u0e48\/\u0e14\u0e33 \u0e43\u0e19\u0e23\u0e38\u0e48\u0e19 EL \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e04\u0e27\u0e32\u0e21\u0e01\u0e27\u0e49\u0e32\u0e07\u0e40\u0e01\u0e34\u0e19\u0e43\u0e04\u0e23 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e35\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e43\u0e2b\u0e21\u0e48\u00a0 \u0e2a\u0e35\u0e02\u0e32\u0e27\u0e41\u0e1e\u0e25\u0e17\u0e34\u0e19\u0e31\u0e21 (\u0e21\u0e38\u0e01) \u0e41\u0e25\u0e30\u0e2a\u0e35\u0e40\u0e17\u0e32\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19\u0e2a\u0e15\u0e35\u0e25 (\u0e40\u0e21\u0e17\u0e31\u0e25\u0e25\u0e34\u0e01)<\/p>\n<p><a href=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-4_resize.jpg\"><img loading=\"lazy\" class=\"alignnone size-large wp-image-9711\" src=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-4_resize-1024x684.jpg\" alt=\"Honda Life Crossover Lifestyle Trip_Swimming (4)_resize\" width=\"1024\" height=\"684\" \/><\/a><\/p>\n<p>\u0e43\u0e19\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e39\u0e48 \u0e2d.\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e21\u0e35\u0e17\u0e31\u0e49\u0e07\u0e16\u0e19\u0e19\u0e17\u0e32\u0e07\u0e15\u0e23\u0e07\u0e41\u0e25\u0e30\u0e17\u0e32\u0e07\u0e42\u0e04\u0e49\u0e07 \u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e31\u0e19\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e2d\u0e2a\u0e22\u0e39\u0e27\u0e35\u0e17\u0e31\u0e49\u0e07 2 \u0e23\u0e38\u0e48\u0e19 \u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e17\u0e31\u0e49\u0e07<strong>\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c<\/strong><strong>-\u0e27\u0e35 \u0e43\u0e2b\u0e21\u0e48 <\/strong>\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e02\u0e19\u0e32\u0e14 <strong>1.5 \u0e25\u0e34\u0e15\u0e23 SOHC i-VTEC 4 \u0e2a\u0e39\u0e1a 16 \u0e27\u0e32\u0e25\u0e4c\u0e27 117 \u0e41\u0e23\u0e07\u0e21\u0e49\u0e32<\/strong> \u00a0\u0e41\u0e25\u0e30<strong>\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c<\/strong><strong>-\u0e27\u0e35<\/strong> \u0e17\u0e35\u0e48\u0e1c\u0e2a\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e40\u0e23\u0e49\u0e32\u0e43\u0e08 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e4c\u0e02\u0e19\u0e32\u0e14 1.8 \u0e25\u0e34\u0e15\u0e23 <strong>SOHC i-VTEC 4 \u0e2a\u0e39\u0e1a 16 \u0e27\u0e32\u0e25\u0e4c\u0e27 141 \u0e41\u0e23\u0e07\u0e21\u0e49\u0e32<\/strong> \u0e42\u0e14\u0e22\u0e17\u0e31\u0e49\u0e07 2 \u0e23\u0e38\u0e48\u0e19 \u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e4c CVT \u0e19\u0e38\u0e48\u0e21\u0e19\u0e27\u0e25\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e17\u0e35\u0e48\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e2d\u0e34\u0e23\u0e4c\u0e18\u0e14\u0e23\u0e35\u0e21 \u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e02\u0e38\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e19\u0e49\u0e33\u0e21\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>E85<\/strong> \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2d\u0e31\u0e19\u0e25\u0e49\u0e33\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e17\u0e38\u0e01\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e07\u0e15\u0e31\u0e27<\/p>\n<p><a href=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-6_resize.jpg\"><img loading=\"lazy\" class=\"size-large wp-image-9712 aligncenter\" src=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-6_resize-1024x684.jpg\" alt=\"Honda Life Crossover Lifestyle Trip_Swimming (6)_resize\" width=\"1024\" height=\"684\" \/><\/a><\/p>\n<p>\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e25\u0e38\u0e22\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e14\u0e49\u0e32\u0e19\u0e17\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e22\u0e19\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e17\u0e31\u0e49\u0e07 2 \u0e23\u0e38\u0e48\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1b\u0e23\u0e31\u0e1a\u0e1e\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e02\u0e19\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e23\u0e30 \u0e17\u0e31\u0e49\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2b\u0e48\u0e27\u0e07\u0e22\u0e32\u0e07 \u0e44\u0e1b\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 \u0e0a\u0e38\u0e48\u0e21\u0e09\u0e48\u0e33\u0e44\u0e1b\u0e01\u0e31\u0e1a\u0e2a\u0e44\u0e25\u0e14\u0e4c\u0e40\u0e14\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e19\u0e34\u0e14 \u0e17\u0e35\u0e48\u0e2a\u0e27\u0e19\u0e19\u0e49\u0e33 \u0e27\u0e32\u0e19\u0e32 \u0e19\u0e32\u0e27\u0e32 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e2d\u0e35\u0e01\u0e27\u0e31\u0e19\u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 <strong>CSR<\/strong> \u0e42\u0e14\u0e22\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e22\u0e30\u0e23\u0e34\u0e21\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14\u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0a\u0e48\u0e27\u0e22\u0e01\u0e31\u0e19\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e19\u0e4c\u0e23\u0e34\u0e21\u0e0a\u0e32\u0e22\u0e2b\u0e32\u0e14\u0e43\u0e2b\u0e49\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e19\u0e38\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 <strong>Cooking Workshop<\/strong> \u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e01\u0e32\u0e23\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e 3 \u0e40\u0e21\u0e19\u0e39\u0e01\u0e31\u0e1a\u0e40\u0e0a\u0e1f\u0e19\u0e1e\u0e14\u0e25 \u0e19\u0e38\u0e0a\u0e40\u0e08\u0e23\u0e34\u0e0d \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19 \u0e01\u0e48\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08<\/p>\n<p><a href=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-8_resize.jpg\"><img loading=\"lazy\" class=\"size-large wp-image-9713 aligncenter\" src=\"https:\/\/www.memagazine.co.th\/wp-content\/uploads\/2019\/09\/Honda-Life-Crossover-Lifestyle-Trip_Swimming-8_resize-1024x701.jpg\" alt=\"\" width=\"1024\" height=\"701\" \/><\/a><\/p>\n<p>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35 \u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e23\u0e37\u0e2d \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e42\u0e0a\u0e27\u0e4c\u0e23\u0e39\u0e21\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e42\u0e17\u0e23 0 2341 7777 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e48\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e32\u0e07 <a href=\"http:\/\/www.honda.co.th\"><strong>www.honda.co.th<\/strong> <\/a>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e17\u0e38\u0e01\u0e23\u0e38\u0e48\u0e19 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e02\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e32\u0e07\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c<a href=\"http:\/\/www.honda.co.th\/testdrive\"><strong> www.honda.co.th\/testdrive<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e0a\u0e34\u0e0d\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 \u201cLife Crossover Lifestyle Trip\u201d \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e22\u0e19\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e40\u0e2d\u0e2a\u0e22\u0e39\u0e27\u0e35 \u0e02\u0e2d\u0e07\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 2 \u0e23\u0e38\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u201c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35 \u0e43\u0e2b\u0e21\u0e48\u201d \u0e41\u0e25\u0e30 \u201c\u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e40\u0e2d\u0e0a\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35\u201d \u0e1a\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u2013 \u0e2b\u0e31\u0e27\u0e2b\u0e34\u0e19 \u0e08.\u0e1b\u0e23\u0e30\u0e08\u0e27\u0e1a\u0e04\u0e35\u0e23\u0e35\u0e02\u0e31\u0e19\u0e18\u0e4c \u0e23\u0e27\u0e21\u0e23\u0e30\u0e22\u0e30\u0e17\u0e32\u0e07\u0e01\u0e27\u0e48\u0e32 400 \u0e01\u0e34\u0e42\u0e25\u0e40\u0e21\u0e15\u0e23 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e38\u0e01\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e23\u0e48\u0e27\u0e21\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e01\u0e0a\u0e2d\u0e1b\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1e\u0e32\u0e04\u0e38\u0e13\u0e04\u0e23\u0e2d\u0e2a\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e14\u0e49\u0e32\u0e19 (Life Crossover) \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32 \u0e04\u0e13\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e1e\u0e1a\u0e01\u0e31\u0e19 \u0e13 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e2d\u0e2d\u0e42\u0e15\u0e42\u0e21\u0e1a\u0e34\u0e25 (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e2a\u0e32\u0e02\u0e32\u0e28\u0e23\u0e35\u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a\u0e22\u0e19\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e40\u0e19\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07 2 \u0e23\u0e38\u0e48\u0e19 \u0e04\u0e37\u0e2d \u0e2e\u0e2d\u0e19\u0e14\u0e49\u0e32 \u0e1a\u0e35\u0e2d\u0e32\u0e23\u0e4c-\u0e27\u0e35 \u0e43\u0e2b\u0e21\u0e48 \u0e22\u0e19\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e04\u0e23\u0e2d\u0e2a\u0e42\u0e2d\u0e40\u0e27\u0e2d\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \u0e41\u0e01\u0e23\u0e48\u0e07\u0e43\u0e19\u0e17\u0e38\u0e01\u0e21\u0e34\u0e15\u0e34 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[19],"tags":[1485,811,1486,1487],"aioseo_notices":[],"views":1251,"_links":{"self":[{"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/posts\/9705"}],"collection":[{"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/comments?post=9705"}],"version-history":[{"count":0,"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/posts\/9705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/media\/11898"}],"wp:attachment":[{"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/media?parent=9705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/categories?post=9705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.memagazine.co.th\/en\/wp-json\/wp\/v2\/tags?post=9705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}